{"id":31223,"date":"2026-02-02T10:58:32","date_gmt":"2026-02-02T10:58:32","guid":{"rendered":"https:\/\/exponor.pt\/eutex-feira-europeia-da-industria-textil-e-moda\/visit\/"},"modified":"2026-02-25T16:07:07","modified_gmt":"2026-02-25T16:07:07","slug":"visit","status":"publish","type":"page","link":"https:\/\/exponor.pt\/en\/eutex-feira-europeia-da-industria-textil-e-moda\/visit\/","title":{"rendered":"Visit"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"31223\" class=\"elementor elementor-31223 elementor-30030\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2744ec30 e-con-full e-flex e-con e-parent\" data-id=\"2744ec30\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-43668e42 elementor-widget elementor-widget-template\" data-id=\"43668e42\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<header data-elementor-type=\"header\" data-elementor-id=\"30014\" class=\"elementor elementor-30014\" data-elementor-post-type=\"elementor_library\">\n\t\t\t<header class=\"elementor-element elementor-element-59e374c shrink-header e-flex e-con-boxed e-con e-parent\" data-id=\"59e374c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;background_motion_fx_opacity_range&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:&quot;4&quot;,&quot;end&quot;:&quot;6&quot;}},&quot;sticky&quot;:&quot;top&quot;,&quot;background_motion_fx_range&quot;:&quot;page&quot;,&quot;background_motion_fx_opacity_effect&quot;:&quot;yes&quot;,&quot;sticky_effects_offset&quot;:&quot;90&quot;,&quot;background_motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_range&quot;:&quot;page&quot;,&quot;background_motion_fx_opacity_direction&quot;:&quot;out-in&quot;,&quot;background_motion_fx_opacity_level&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;background_motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<a class=\"elementor-element elementor-element-38a92d5 e-con-full back_to_exponor e-flex e-con e-child\" data-id=\"38a92d5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;position&quot;:&quot;absolute&quot;}\" href=\"\/\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f85c6da back_icon elementor-widget elementor-widget-html\" data-id=\"f85c6da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"icon-park-outline--to-left\"><\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-58718eb elementor-widget elementor-widget-image\" data-id=\"58718eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"297\" height=\"300\" src=\"https:\/\/exponor.pt\/wp-content\/uploads\/2025\/05\/logo_branco_quadrado-e1741020245400-297x300.png\" class=\"attachment-medium size-medium wp-image-25232\" alt=\"\" srcset=\"https:\/\/exponor.pt\/wp-content\/uploads\/2025\/05\/logo_branco_quadrado-e1741020245400-297x300.png 297w, https:\/\/exponor.pt\/wp-content\/uploads\/2025\/05\/logo_branco_quadrado-e1741020245400-1014x1024.png 1014w, https:\/\/exponor.pt\/wp-content\/uploads\/2025\/05\/logo_branco_quadrado-e1741020245400-768x775.png 768w, https:\/\/exponor.pt\/wp-content\/uploads\/2025\/05\/logo_branco_quadrado-e1741020245400.png 1250w\" sizes=\"(max-width: 297px) 100vw, 297px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<div class=\"elementor-element elementor-element-eaf670c e-con-full e-flex e-con e-child\" data-id=\"eaf670c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e21da29 elementor-widget elementor-widget-image\" data-id=\"e21da29\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"\/eutex-industria-textil-moda\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"198\" height=\"158\" src=\"https:\/\/exponor.pt\/wp-content\/uploads\/2026\/02\/logo_eutex-e1770035657502.png\" class=\"attachment-2048x2048 size-2048x2048 wp-image-30104\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e917f1a e-con-full e-flex e-con e-child\" data-id=\"e917f1a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-eb3be3c elementor-nav-menu--stretch elementor-nav-menu__align-end elementor-nav-menu--dropdown-mobile elementor-nav-menu__text-align-aside elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-nav-menu\" data-id=\"eb3be3c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;full_width&quot;:&quot;stretch&quot;,&quot;layout&quot;:&quot;horizontal&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;svg aria-hidden=\\&quot;true\\&quot; class=\\&quot;e-font-icon-svg e-fas-caret-down\\&quot; viewBox=\\&quot;0 0 320 512\\&quot; xmlns=\\&quot;http:\\\/\\\/www.w3.org\\\/2000\\\/svg\\&quot;&gt;&lt;path d=\\&quot;M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\\&quot;&gt;&lt;\\\/path&gt;&lt;\\\/svg&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Menu\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-text e--animation-none\">\n\t\t\t\t<ul id=\"menu-1-eb3be3c\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30024\"><a href=\"https:\/\/exponor.pt\/eutex-industria-textil-moda\/sobre-a-feira\/\" class=\"elementor-item\">Discover EUTEX<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30087\"><a href=\"https:\/\/exponor.pt\/eutex-industria-textil-moda\/contactos-2\/\" class=\"elementor-item\">Contact the EUTEX team<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Menu Toggle\" aria-expanded=\"false\">\n\t\t\t<svg aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open e-font-icon-svg e-eicon-menu-bar\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M104 333H896C929 333 958 304 958 271S929 208 896 208H104C71 208 42 237 42 271S71 333 104 333ZM104 583H896C929 583 958 554 958 521S929 458 896 458H104C71 458 42 487 42 521S71 583 104 583ZM104 833H896C929 833 958 804 958 771S929 708 896 708H104C71 708 42 737 42 771S71 833 104 833Z\"><\/path><\/svg><svg aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close e-font-icon-svg e-eicon-close\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M742 167L500 408 258 167C246 154 233 150 217 150 196 150 179 158 167 167 154 179 150 196 150 212 150 229 154 242 171 254L408 500 167 742C138 771 138 800 167 829 196 858 225 858 254 829L496 587 738 829C750 842 767 846 783 846 800 846 817 842 829 829 842 817 846 804 846 783 846 767 842 750 829 737L588 500 833 258C863 229 863 200 833 171 804 137 775 137 742 167Z\"><\/path><\/svg>\t\t<\/div>\n\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-eb3be3c\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30024\"><a href=\"https:\/\/exponor.pt\/eutex-industria-textil-moda\/sobre-a-feira\/\" class=\"elementor-item\" tabindex=\"-1\">Discover EUTEX<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30087\"><a href=\"https:\/\/exponor.pt\/eutex-industria-textil-moda\/contactos-2\/\" class=\"elementor-item\" tabindex=\"-1\">Contact the EUTEX team<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c86fe9 elementor-widget elementor-widget-wpml-language-switcher\" data-id=\"4c86fe9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wpml-language-switcher.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wpml-elementor-ls\">\n<div role=\"navigation\" aria-label=\"Language Switcher\" class=\"wpml-ls-statics-shortcode_actions wpml-ls wpml-ls-legacy-dropdown-click js-wpml-ls-legacy-dropdown-click\">\n\t<ul>\n\n\t\t<li class=\"wpml-ls-slot-shortcode_actions wpml-ls-item wpml-ls-item-en wpml-ls-current-language wpml-ls-last-item wpml-ls-item-legacy-dropdown-click\">\n\n\t\t\t<a href=\"#\" hreflang=\"\" lang=\"\" class=\"js-wpml-ls-item-toggle wpml-ls-item-toggle\" aria-expanded=\"false\" aria-controls=\"wpml-ls-submenu-click-default\" aria-haspopup=\"true\" aria-label=\"Language switcher, click to open then tab to navigate\" tabindex=\"0\" role=\"button\" title=\"Switch to English\">\n\t\t\t\t                                    <img decoding=\"async\"\n            class=\"wpml-ls-flag\"\n            src=\"https:\/\/exponor.pt\/wp-content\/plugins\/sitepress-multilingual-cms\/res\/flags\/en.svg\"\n            alt=\"English\"\n            loading=\"lazy\"\n            width=18\n            height=12\n    \/><\/a>\n\n\t\t\t<ul id=\"wpml-ls-submenu-click-default\" class=\"js-wpml-ls-sub-menu wpml-ls-sub-menu\">\n\t\t\t\t\n\t\t\t\t\t<li class=\"wpml-ls-slot-shortcode_actions wpml-ls-item wpml-ls-item-pt-pt wpml-ls-first-item\">\n\t\t\t\t\t\t<a href=\"https:\/\/exponor.pt\/\" hreflang=\"pt-pt\" lang=\"pt-pt\" class=\"wpml-ls-link\" aria-label=\"Switch to Portuguese\" title=\"Switch to Portuguese\">\n\t\t\t\t\t\t\t                                    <img decoding=\"async\"\n            class=\"wpml-ls-flag\"\n            src=\"https:\/\/exponor.pt\/wp-content\/plugins\/sitepress-multilingual-cms\/res\/flags\/pt-pt.svg\"\n            alt=\"Portuguese\"\n            loading=\"lazy\"\n            width=18\n            height=12\n    \/><\/a>\n\t\t\t\t\t<\/li>\n\n\t\t\t\t\t\t\t<\/ul>\n\n\t\t<\/li>\n\n\t<\/ul>\n<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/header>\n\t\t\t\t<\/header>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ce2ab40 e-flex e-con-boxed e-con e-parent\" data-id=\"ce2ab40\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4673c16d e-con-full e-flex e-con e-child\" data-id=\"4673c16d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-480334ab elementor-widget elementor-widget-heading\" data-id=\"480334ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Visit<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-761ccd46 e-con-full e-flex e-con e-child\" data-id=\"761ccd46\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-3d87d128 e-con-full e-flex e-con e-child\" data-id=\"3d87d128\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-7c5ab42e e-con-full e-flex e-con e-child\" data-id=\"7c5ab42e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6403eb0f elementor-widget elementor-widget-heading\" data-id=\"6403eb0f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Entre em contacto com a equipa da EUTEX<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d0b9121 elementor-widget elementor-widget-text-editor\" data-id=\"3d0b9121\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Participating in EUTEX opens the door to the future of the textile industry. Discover new collections, find emerging talent, and establish contacts that will make a difference to your business. <\/p><ul><li>Stay updated with market news.<\/li><li>Establish business relationships with leading brands and suppliers.<\/li><li>Inspire-se com as tend\u00eancias de sustentabilidade e inova\u00e7\u00e3o.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2cfc0941 e-con-full e-flex e-con e-child\" data-id=\"2cfc0941\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7b6a682a elementor-widget elementor-widget-image\" data-id=\"7b6a682a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;],&quot;motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:4,&quot;sizes&quot;:[]},&quot;motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}}}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"220\" src=\"https:\/\/exponor.pt\/wp-content\/uploads\/2026\/02\/BANNERS-1851X507PX-03-1024x281.jpg\" class=\"attachment-large size-large wp-image-31199\" alt=\"\" srcset=\"https:\/\/exponor.pt\/wp-content\/uploads\/2026\/02\/BANNERS-1851X507PX-03-1024x281.jpg 1024w, https:\/\/exponor.pt\/wp-content\/uploads\/2026\/02\/BANNERS-1851X507PX-03-300x82.jpg 300w, https:\/\/exponor.pt\/wp-content\/uploads\/2026\/02\/BANNERS-1851X507PX-03-768x211.jpg 768w, https:\/\/exponor.pt\/wp-content\/uploads\/2026\/02\/BANNERS-1851X507PX-03-1536x421.jpg 1536w, https:\/\/exponor.pt\/wp-content\/uploads\/2026\/02\/BANNERS-1851X507PX-03-2048x561.jpg 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4e67307 e-flex e-con-boxed e-con e-parent\" data-id=\"4e67307\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-778f88a9 elementor-widget elementor-widget-heading\" data-id=\"778f88a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">What will you find?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-335180a8 e-flex e-con-boxed e-con e-parent\" data-id=\"335180a8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7c0678a8 e-con-full e-grid e-con e-child\" data-id=\"7c0678a8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-384d96a e-con-full animated-slow e-flex elementor-invisible e-con e-child\" data-id=\"384d96a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_mobile&quot;:&quot;none&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-92fe9db elementor-widget elementor-widget-image-box\" data-id=\"92fe9db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Be inspired by trends in sustainability and innovation.<\/h3><p class=\"elementor-image-box-description\">The European textile industry is in the spotlight, combining tradition, technology, and sustainable design. EUTEX is the perfect showcase to discover the latest trends and opportunities in the market. <\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1ef67ee3 e-con-full animated-slow e-flex elementor-invisible e-con e-child\" data-id=\"1ef67ee3\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_mobile&quot;:&quot;none&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7ea6e5eb elementor-widget elementor-widget-image-box\" data-id=\"7ea6e5eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Innovation and sustainability in focus.<\/h3><p class=\"elementor-image-box-description\">The 2025 edition highlights emerging trends such as sustainable design, new materials, and technologies applied to fashion.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-29d2b453 e-con-full animated-slow e-flex elementor-invisible e-con e-child\" data-id=\"29d2b453\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_mobile&quot;:&quot;none&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-49bdb185 elementor-widget elementor-widget-image-box\" data-id=\"49bdb185\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Business and inspiration<\/h3><p class=\"elementor-image-box-description\">Find new suppliers, strengthen business relationships, and be inspired by the solutions and ideas that are shaping the future of the industry.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6d96eff e-flex e-con-boxed e-con e-parent\" data-id=\"6d96eff\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-19f183d elementor-widget elementor-widget-template\" data-id=\"19f183d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"container\" data-elementor-id=\"33671\" class=\"elementor elementor-33671 elementor-30485 elementor-30485\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4075aca3 animated-slow e-flex e-con-boxed elementor-invisible e-con e-parent\" data-id=\"4075aca3\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_mobile&quot;:&quot;none&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-17bf99c1 e-con-full e-grid e-con e-child\" data-id=\"17bf99c1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-4a04605f e-con-full e-flex e-con e-child\" data-id=\"4a04605f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-10403b8a elementor-widget elementor-widget-heading\" data-id=\"10403b8a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Travel at a discount!<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5e2acbf3 e-con-full e-flex e-con e-child\" data-id=\"5e2acbf3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4db5619c elementor-widget elementor-widget-text-editor\" data-id=\"4db5619c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"x_elementToProof\" data-olk-copy-source=\"MessageBody\"><strong>Exponor has teamed up with FlixBus to make your visit to the fair easier!&nbsp;<\/strong>All our visitors are entitled to a discount on FlixBus coach journeys to Porto.<\/div>\n<div data-olk-copy-source=\"MessageBody\">&nbsp;<\/div>\n<div data-olk-copy-source=\"MessageBody\"><strong>Discounts available<\/strong><\/div>\n<div class=\"x_elementToProof\">\n<ul>\n<li>20% discount \u2013 Domestic travel (Portugal \u2192 Porto)<br>Discount valid for journeys within Portugal to Porto.<\/li>\n<li>10% discount \u2013 International travel (including Spain and the rest of the FlixBus network)<br>This discount applies to international journeys, including routes to and from Spain and other destinations on the FlixBus network.<\/li>\n<\/ul>\n<div>&nbsp;<\/div>\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-27e57aa elementor-widget elementor-widget-button\" data-id=\"27e57aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.hiphiphour.com\/a5a29cdcd17983e01133\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">DISCOUNT ON DOMESTIC TRAVEL<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0d0e2f9 elementor-widget elementor-widget-button\" data-id=\"0d0e2f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.hiphiphour.com\/eb47f5c9b96b5fc1fdd5\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">INTERNATIONAL TRAVEL DISCOUNT<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-45c80bf1 e-con-full e-flex e-con e-child\" data-id=\"45c80bf1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e608a07 elementor-widget elementor-widget-image\" data-id=\"e608a07\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"300\" src=\"https:\/\/exponor.pt\/wp-content\/uploads\/2025\/12\/mobile-flix-hero-q4-2021.jpg\" class=\"attachment-large size-large wp-image-32318\" alt=\"\" srcset=\"https:\/\/exponor.pt\/wp-content\/uploads\/2025\/12\/mobile-flix-hero-q4-2021.jpg 600w, https:\/\/exponor.pt\/wp-content\/uploads\/2025\/12\/mobile-flix-hero-q4-2021-300x150.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7e9d1c5 elementor-widget elementor-widget-text-editor\" data-id=\"7e9d1c5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"x_elementToProof\"><p><b>How does it work?<\/b><\/p><\/div><ol start=\"1\" data-start=\"575\" data-end=\"837\"><li><p>Select the discount option that applies to your journey (domestic or international).<\/p><\/li><li><p>Visit the relevant page and get your unique code.<\/p><\/li><li><p>Check timetables and book your journey on the FlixBus website or app.<\/p><\/li><li><p>Enter the code at checkout to receive an instant discount.<\/p><\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3a388bde e-con-full e-flex e-con e-parent\" data-id=\"3a388bde\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2b7c7006 elementor-widget elementor-widget-template\" data-id=\"2b7c7006\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"container\" data-elementor-id=\"25341\" class=\"elementor elementor-25341 elementor-16422 elementor-16422\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t<div class=\"elementor-element elementor-element-34cd4981 e-flex e-con-boxed e-con e-parent\" data-id=\"34cd4981\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-23724844 e-con-full e-flex e-con e-child\" data-id=\"23724844\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-1dfca7e6 e-con-full e-flex e-con e-child\" data-id=\"1dfca7e6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-7bb01a5a e-con-full e-flex e-con e-child\" data-id=\"7bb01a5a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-204e261f elementor-widget elementor-widget-heading\" data-id=\"204e261f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">How to get there<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d0dc35a elementor-widget elementor-widget-text-editor\" data-id=\"5d0dc35a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>The Exponor exhibition center is strategically located just 15 minutes from the city of Porto, an important urban business and industrial center and gateway to a strong economic region, and 10 minutes from Francisco S\u00e1 Carneiro International Airport.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3844a6f9 e-con-full e-flex e-con e-child\" data-id=\"3844a6f9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-181af7d2 e-con-full e-flex e-con e-child\" data-id=\"181af7d2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-231a3ed4 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"231a3ed4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">STCP buses stopping at Exponor:\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1d1e03c0 elementor-widget elementor-widget-text-editor\" data-id=\"1d1e03c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><a href=\"https:\/\/www.stcp.pt\/pt\/viajar\/linhas\/?linha=601&amp;sentido=0&amp;t=horarios\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">601<\/a>, stop \u201cExponor\u201d (Cordoaria \u2013 Airport Line, via Mar Shopping)<\/li><li><a href=\"https:\/\/www.stcp.pt\/pt\/viajar\/linhas\/?linha=507&amp;sentido=0&amp;t=horarios\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">507<\/a>, Cordoaria \u2013 Mar Shopping Line<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-734d455a e-con-full e-flex e-con e-child\" data-id=\"734d455a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-298cc097 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"298cc097\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nearest metro station with bus connections:\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-16306538 elementor-widget elementor-widget-text-editor\" data-id=\"16306538\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>Casa da M\u00fasica Station<\/li><li>Senhor de Matosinhos Station<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-234500e6 e-con-full e-flex e-con e-child\" data-id=\"234500e6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-7352ef78 e-con-full e-flex e-con e-child\" data-id=\"7352ef78\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-535cfecd elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"535cfecd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Arriving at Exponor<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8c5339f elementor-widget elementor-widget-text-editor\" data-id=\"8c5339f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>A1 + A28, exit \u201cExponor\u201d<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-618ceb96 e-con-full e-flex e-con e-child\" data-id=\"618ceb96\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-3538cfc e-con-full e-flex e-con e-child\" data-id=\"3538cfc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-be0d28c elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"be0d28c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Where to stay<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ddaa54 elementor-widget elementor-widget-text-editor\" data-id=\"2ddaa54\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><a href=\"https:\/\/exponor.pt\/en\/general-information\/\"><span style=\"text-decoration: underline\">Click to see the hotels<\/span><\/a><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-656d2e72 e-con-full e-flex e-con e-child\" data-id=\"656d2e72\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6a090c12 elementor-widget elementor-widget-google_maps\" data-id=\"6a090c12\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=exponor&#038;t=m&#038;z=15&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"exponor\"\n\t\t\t\t\taria-label=\"exponor\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-467ec9c7 e-con-full e-flex e-con e-parent\" data-id=\"467ec9c7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-25267d7a elementor-widget elementor-widget-template\" data-id=\"25267d7a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"container\" data-elementor-id=\"31230\" class=\"elementor elementor-31230 elementor-30045 elementor-30045\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1234e70 e-flex e-con-boxed e-con e-parent\" data-id=\"1234e70\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5b28620 e-con-full e-flex e-con e-child\" data-id=\"5b28620\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-3fc6e83 e-con-full e-flex e-con e-child\" data-id=\"3fc6e83\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-06b89cb elementor-widget elementor-widget-heading\" data-id=\"06b89cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Subscribe to our newsletter<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dc616d7 elementor-widget elementor-widget-html\" data-id=\"dc616d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"eg-embed-4efe8bOs\"><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-04789fd e-con-full e-flex e-con e-child\" data-id=\"04789fd\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-62f2388f e-con-full e-flex e-con e-parent\" data-id=\"62f2388f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5fdfa982 elementor-widget elementor-widget-template\" data-id=\"5fdfa982\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<footer data-elementor-type=\"footer\" data-elementor-id=\"30039\" class=\"elementor elementor-30039\" data-elementor-post-type=\"elementor_library\">\n\t\t\t<div class=\"elementor-element elementor-element-0283153 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"0283153\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-69cdde9 e-flex e-con-boxed e-con e-parent\" data-id=\"69cdde9\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-920701c e-con-full e-flex e-con e-child\" data-id=\"920701c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-0df2124 e-con-full e-flex e-con e-child\" data-id=\"0df2124\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-d31e899 e-con-full e-flex e-con e-child\" data-id=\"d31e899\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-78965ac elementor-widget elementor-widget-image\" data-id=\"78965ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"198\" height=\"158\" src=\"https:\/\/exponor.pt\/wp-content\/uploads\/2026\/02\/logo_eutex-e1770035657502.png\" class=\"attachment-full size-full wp-image-30104\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c3e4764 elementor-widget elementor-widget-text-editor\" data-id=\"c3e4764\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Evento profissional dedicado ao setor t\u00eaxtil e moda. De 23 e 24 de setembro, na Exponor.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ccb078f elementor-widget elementor-widget-heading\" data-id=\"ccb078f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">2026 \u00a9 todos os direitos reservados <\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-464a357 e-con-full e-flex e-con e-child\" data-id=\"464a357\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6380cbd elementor-widget elementor-widget-heading\" data-id=\"6380cbd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Links \u00dateis<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-af42026 elementor-widget elementor-widget-nav-menu\" data-id=\"af42026\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;dropdown&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;svg aria-hidden=\\&quot;true\\&quot; class=\\&quot;e-font-icon-svg e-fas-caret-down\\&quot; viewBox=\\&quot;0 0 320 512\\&quot; xmlns=\\&quot;http:\\\/\\\/www.w3.org\\\/2000\\\/svg\\&quot;&gt;&lt;path d=\\&quot;M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\\&quot;&gt;&lt;\\\/path&gt;&lt;\\\/svg&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;}}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-af42026\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30024\"><a href=\"https:\/\/exponor.pt\/eutex-industria-textil-moda\/sobre-a-feira\/\" class=\"elementor-item\" tabindex=\"-1\">Discover EUTEX<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30087\"><a href=\"https:\/\/exponor.pt\/eutex-industria-textil-moda\/contactos-2\/\" class=\"elementor-item\" tabindex=\"-1\">Contact the EUTEX team<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4dfb3a0 e-con-full e-flex e-con e-child\" data-id=\"4dfb3a0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3376d8e elementor-widget elementor-widget-heading\" data-id=\"3376d8e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Contacte-nos<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d42a6c elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"5d42a6c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"tel:351229981400\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">+351 229 981 400 <br> <small>(chamada para rede fixa nacional)<\/small><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"mailto:info@exponor.pt\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">info@exponor.pt<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-008c754 elementor-widget elementor-widget-heading\" data-id=\"008c754\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Redes Sociais<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e4d22f8 elementor-shape-circle e-grid-align-left elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"e4d22f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook-f elementor-repeater-item-09852b9\" href=\"https:\/\/www.facebook.com\/eutex.exponor\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook-f<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-facebook-f\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M279.14 288l14.22-92.66h-88.91v-60.13c0-25.35 12.42-50.06 52.24-50.06h40.42V6.26S260.43 0 225.36 0c-73.22 0-121.08 44.38-121.08 124.72v70.62H22.89V288h81.39v224h100.17V288z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-d41ab1a\" href=\"https:\/\/www.instagram.com\/eutex.exponor\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-instagram\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.1 141c-63.6 0-114.9 51.3-114.9 114.9s51.3 114.9 114.9 114.9S339 319.5 339 255.9 287.7 141 224.1 141zm0 189.6c-41.1 0-74.7-33.5-74.7-74.7s33.5-74.7 74.7-74.7 74.7 33.5 74.7 74.7-33.6 74.7-74.7 74.7zm146.4-194.3c0 14.9-12 26.8-26.8 26.8-14.9 0-26.8-12-26.8-26.8s12-26.8 26.8-26.8 26.8 12 26.8 26.8zm76.1 27.2c-1.7-35.9-9.9-67.7-36.2-93.9-26.2-26.2-58-34.4-93.9-36.2-37-2.1-147.9-2.1-184.9 0-35.8 1.7-67.6 9.9-93.9 36.1s-34.4 58-36.2 93.9c-2.1 37-2.1 147.9 0 184.9 1.7 35.9 9.9 67.7 36.2 93.9s58 34.4 93.9 36.2c37 2.1 147.9 2.1 184.9 0 35.9-1.7 67.7-9.9 93.9-36.2 26.2-26.2 34.4-58 36.2-93.9 2.1-37 2.1-147.8 0-184.8zM398.8 388c-7.8 19.6-22.9 34.7-42.6 42.6-29.5 11.7-99.5 9-132.1 9s-102.7 2.6-132.1-9c-19.6-7.8-34.7-22.9-42.6-42.6-11.7-29.5-9-99.5-9-132.1s-2.6-102.7 9-132.1c7.8-19.6 22.9-34.7 42.6-42.6 29.5-11.7 99.5-9 132.1-9s102.7-2.6 132.1 9c19.6 7.8 34.7 22.9 42.6 42.6 11.7 29.5 9 99.5 9 132.1s2.7 102.7-9 132.1z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-98dce4a e-con-full e-flex e-con e-child\" data-id=\"98dce4a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-3d65691 e-con-full e-flex e-con e-child\" data-id=\"3d65691\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dc6efe8 elementor-widget elementor-widget-heading\" data-id=\"dc6efe8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Legal<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c94792 elementor-nav-menu--dropdown-none elementor-widget elementor-widget-nav-menu\" data-id=\"0c94792\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;vertical&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;svg aria-hidden=\\&quot;true\\&quot; class=\\&quot;e-font-icon-svg e-fas-caret-down\\&quot; viewBox=\\&quot;0 0 320 512\\&quot; xmlns=\\&quot;http:\\\/\\\/www.w3.org\\\/2000\\\/svg\\&quot;&gt;&lt;path d=\\&quot;M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\\&quot;&gt;&lt;\\\/path&gt;&lt;\\\/svg&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;}}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Menu\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-vertical e--pointer-none\">\n\t\t\t\t<ul id=\"menu-1-0c94792\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-27282\"><a target=\"_blank\" href=\"https:\/\/exponor.pt\/en\/privacy-policy\/\" class=\"elementor-item\">Privacy Policy<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-27283\"><a target=\"_blank\" href=\"https:\/\/exponor.pt\/en\/terms-and-conditions\/\" class=\"elementor-item\">Terms and Conditions<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-0c94792\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-27282\"><a target=\"_blank\" href=\"https:\/\/exponor.pt\/en\/privacy-policy\/\" class=\"elementor-item\" tabindex=\"-1\">Privacy Policy<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-27283\"><a target=\"_blank\" href=\"https:\/\/exponor.pt\/en\/terms-and-conditions\/\" class=\"elementor-item\" tabindex=\"-1\">Terms and Conditions<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d074a14 e-con-full e-flex e-con e-child\" data-id=\"d074a14\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2cfd2ab elementor-widget elementor-widget-image\" data-id=\"2cfd2ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.aeportugal.pt\/pt\/home\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"152\" height=\"26\" src=\"https:\/\/exponor.pt\/wp-content\/uploads\/2025\/05\/logo_branco_aep.png\" class=\"attachment-large size-large wp-image-25238\" alt=\"\" srcset=\"https:\/\/exponor.pt\/wp-content\/uploads\/2025\/05\/logo_branco_aep.png 152w, https:\/\/exponor.pt\/wp-content\/uploads\/2025\/05\/logo_branco_aep-150x26.png 150w\" sizes=\"(max-width: 152px) 100vw, 152px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0345309 elementor-widget elementor-widget-image\" data-id=\"0345309\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"276\" height=\"81\" src=\"https:\/\/exponor.pt\/wp-content\/uploads\/2025\/05\/LOGO-SEC-EXPONOR-BRANCO-e1735843866133.png\" class=\"attachment-large size-large wp-image-25239\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/footer>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Visit Entre em contacto com a equipa da EUTEX Participating in EUTEX opens the door to the future of the textile industry. Discover new collections, find emerging talent, and establish contacts that will make a difference to your business. Stay updated with market news. Establish business relationships with leading brands and suppliers. Inspire-se com as [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":31197,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-31223","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Visit - Exponor<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exponor.pt\/en\/eutex-feira-europeia-da-industria-textil-e-moda\/visit\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Visit - Exponor\" \/>\n<meta property=\"og:description\" content=\"Visit Entre em contacto com a equipa da EUTEX Participating in EUTEX opens the door to the future of the textile industry. Discover new collections, find emerging talent, and establish contacts that will make a difference to your business. Stay updated with market news. Establish business relationships with leading brands and suppliers. Inspire-se com as [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exponor.pt\/en\/eutex-feira-europeia-da-industria-textil-e-moda\/visit\/\" \/>\n<meta property=\"og:site_name\" content=\"Exponor\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/exponor.fiporto\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-25T16:07:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exponor.pt\/wp-content\/uploads\/2026\/02\/BANNERS-1851X507PX-03-1024x281.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exponor.pt\\\/en\\\/eutex-feira-europeia-da-industria-textil-e-moda\\\/visit\\\/\",\"url\":\"https:\\\/\\\/exponor.pt\\\/en\\\/eutex-feira-europeia-da-industria-textil-e-moda\\\/visit\\\/\",\"name\":\"Visit - Exponor\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exponor.pt\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exponor.pt\\\/en\\\/eutex-feira-europeia-da-industria-textil-e-moda\\\/visit\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exponor.pt\\\/en\\\/eutex-feira-europeia-da-industria-textil-e-moda\\\/visit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exponor.pt\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/BANNERS-1851X507PX-03-1024x281.jpg\",\"datePublished\":\"2026-02-02T10:58:32+00:00\",\"dateModified\":\"2026-02-25T16:07:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exponor.pt\\\/en\\\/eutex-feira-europeia-da-industria-textil-e-moda\\\/visit\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exponor.pt\\\/en\\\/eutex-feira-europeia-da-industria-textil-e-moda\\\/visit\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/exponor.pt\\\/en\\\/eutex-feira-europeia-da-industria-textil-e-moda\\\/visit\\\/#primaryimage\",\"url\":\"https:\\\/\\\/exponor.pt\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/BANNERS-1851X507PX-03-1024x281.jpg\",\"contentUrl\":\"https:\\\/\\\/exponor.pt\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/BANNERS-1851X507PX-03-1024x281.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exponor.pt\\\/en\\\/eutex-feira-europeia-da-industria-textil-e-moda\\\/visit\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/exponor.pt\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EUTEX &#8211; Feira Europeia da Ind\u00fastria T\u00eaxtil e Moda\",\"item\":\"https:\\\/\\\/exponor.pt\\\/en\\\/eutex-feira-europeia-da-industria-textil-e-moda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Visit\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exponor.pt\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/exponor.pt\\\/en\\\/\",\"name\":\"Exponor\",\"description\":\"Feira Internacional do Porto\",\"publisher\":{\"@id\":\"https:\\\/\\\/exponor.pt\\\/en\\\/#organization\"},\"alternateName\":\"Feira Internacional do Porto\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exponor.pt\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/exponor.pt\\\/en\\\/#organization\",\"name\":\"Exponor\",\"alternateName\":\"Feira Internacional do Porto\",\"url\":\"https:\\\/\\\/exponor.pt\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/exponor.pt\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/exponor.pt\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/FavIcon.jpg\",\"contentUrl\":\"https:\\\/\\\/exponor.pt\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/FavIcon.jpg\",\"width\":500,\"height\":499,\"caption\":\"Exponor\"},\"image\":{\"@id\":\"https:\\\/\\\/exponor.pt\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/exponor.fiporto\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/exponor-fiporto\",\"https:\\\/\\\/www.instagram.com\\\/exponor.porto\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/EXPONORtv\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Visit - Exponor","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exponor.pt\/en\/eutex-feira-europeia-da-industria-textil-e-moda\/visit\/","og_locale":"en_US","og_type":"article","og_title":"Visit - Exponor","og_description":"Visit Entre em contacto com a equipa da EUTEX Participating in EUTEX opens the door to the future of the textile industry. Discover new collections, find emerging talent, and establish contacts that will make a difference to your business. Stay updated with market news. Establish business relationships with leading brands and suppliers. Inspire-se com as [&hellip;]","og_url":"https:\/\/exponor.pt\/en\/eutex-feira-europeia-da-industria-textil-e-moda\/visit\/","og_site_name":"Exponor","article_publisher":"https:\/\/www.facebook.com\/exponor.fiporto\/","article_modified_time":"2026-02-25T16:07:07+00:00","og_image":[{"url":"https:\/\/exponor.pt\/wp-content\/uploads\/2026\/02\/BANNERS-1851X507PX-03-1024x281.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/exponor.pt\/en\/eutex-feira-europeia-da-industria-textil-e-moda\/visit\/","url":"https:\/\/exponor.pt\/en\/eutex-feira-europeia-da-industria-textil-e-moda\/visit\/","name":"Visit - Exponor","isPartOf":{"@id":"https:\/\/exponor.pt\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exponor.pt\/en\/eutex-feira-europeia-da-industria-textil-e-moda\/visit\/#primaryimage"},"image":{"@id":"https:\/\/exponor.pt\/en\/eutex-feira-europeia-da-industria-textil-e-moda\/visit\/#primaryimage"},"thumbnailUrl":"https:\/\/exponor.pt\/wp-content\/uploads\/2026\/02\/BANNERS-1851X507PX-03-1024x281.jpg","datePublished":"2026-02-02T10:58:32+00:00","dateModified":"2026-02-25T16:07:07+00:00","breadcrumb":{"@id":"https:\/\/exponor.pt\/en\/eutex-feira-europeia-da-industria-textil-e-moda\/visit\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exponor.pt\/en\/eutex-feira-europeia-da-industria-textil-e-moda\/visit\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/exponor.pt\/en\/eutex-feira-europeia-da-industria-textil-e-moda\/visit\/#primaryimage","url":"https:\/\/exponor.pt\/wp-content\/uploads\/2026\/02\/BANNERS-1851X507PX-03-1024x281.jpg","contentUrl":"https:\/\/exponor.pt\/wp-content\/uploads\/2026\/02\/BANNERS-1851X507PX-03-1024x281.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/exponor.pt\/en\/eutex-feira-europeia-da-industria-textil-e-moda\/visit\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/exponor.pt\/en\/"},{"@type":"ListItem","position":2,"name":"EUTEX &#8211; Feira Europeia da Ind\u00fastria T\u00eaxtil e Moda","item":"https:\/\/exponor.pt\/en\/eutex-feira-europeia-da-industria-textil-e-moda\/"},{"@type":"ListItem","position":3,"name":"Visit"}]},{"@type":"WebSite","@id":"https:\/\/exponor.pt\/en\/#website","url":"https:\/\/exponor.pt\/en\/","name":"Exponor","description":"Feira Internacional do Porto","publisher":{"@id":"https:\/\/exponor.pt\/en\/#organization"},"alternateName":"Feira Internacional do Porto","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exponor.pt\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/exponor.pt\/en\/#organization","name":"Exponor","alternateName":"Feira Internacional do Porto","url":"https:\/\/exponor.pt\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/exponor.pt\/en\/#\/schema\/logo\/image\/","url":"https:\/\/exponor.pt\/wp-content\/uploads\/2025\/05\/FavIcon.jpg","contentUrl":"https:\/\/exponor.pt\/wp-content\/uploads\/2025\/05\/FavIcon.jpg","width":500,"height":499,"caption":"Exponor"},"image":{"@id":"https:\/\/exponor.pt\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/exponor.fiporto\/","https:\/\/www.linkedin.com\/company\/exponor-fiporto","https:\/\/www.instagram.com\/exponor.porto\/","https:\/\/www.youtube.com\/user\/EXPONORtv"]}]}},"_links":{"self":[{"href":"https:\/\/exponor.pt\/en\/wp-json\/wp\/v2\/pages\/31223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exponor.pt\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/exponor.pt\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/exponor.pt\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/exponor.pt\/en\/wp-json\/wp\/v2\/comments?post=31223"}],"version-history":[{"count":2,"href":"https:\/\/exponor.pt\/en\/wp-json\/wp\/v2\/pages\/31223\/revisions"}],"predecessor-version":[{"id":31225,"href":"https:\/\/exponor.pt\/en\/wp-json\/wp\/v2\/pages\/31223\/revisions\/31225"}],"up":[{"embeddable":true,"href":"https:\/\/exponor.pt\/en\/wp-json\/wp\/v2\/pages\/31197"}],"wp:attachment":[{"href":"https:\/\/exponor.pt\/en\/wp-json\/wp\/v2\/media?parent=31223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}