{"id":259,"count":1,"description":"","link":"https:\/\/exponor.pt\/en\/organizador_calendario\/onevents\/","name":"OnEvents","slug":"onevents","taxonomy":"organizador_calendario","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>OnEvents Archives - Exponor<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"OnEvents Archives - Exponor\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exponor.pt\/en\/organizador_calendario\/onevents\/\" \/>\n<meta property=\"og:site_name\" content=\"Exponor\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exponor.pt\/wp-content\/uploads\/2025\/06\/redesociais_exponor.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/exponor.pt\\\/en\\\/organizador_calendario\\\/onevents\\\/\",\"url\":\"https:\\\/\\\/exponor.pt\\\/en\\\/organizador_calendario\\\/onevents\\\/\",\"name\":\"OnEvents Archives - Exponor\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exponor.pt\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exponor.pt\\\/en\\\/organizador_calendario\\\/onevents\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exponor.pt\\\/en\\\/organizador_calendario\\\/onevents\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/exponor.pt\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"OnEvents\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exponor.pt\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/exponor.pt\\\/en\\\/\",\"name\":\"Exponor\",\"description\":\"Feira Internacional do Porto\",\"publisher\":{\"@id\":\"https:\\\/\\\/exponor.pt\\\/en\\\/#organization\"},\"alternateName\":\"Feira Internacional do Porto\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exponor.pt\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/exponor.pt\\\/en\\\/#organization\",\"name\":\"Exponor\",\"alternateName\":\"Feira Internacional do Porto\",\"url\":\"https:\\\/\\\/exponor.pt\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/exponor.pt\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/exponor.pt\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/FavIcon.jpg\",\"contentUrl\":\"https:\\\/\\\/exponor.pt\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/FavIcon.jpg\",\"width\":500,\"height\":499,\"caption\":\"Exponor\"},\"image\":{\"@id\":\"https:\\\/\\\/exponor.pt\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/exponor.fiporto\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/exponor-fiporto\",\"https:\\\/\\\/www.instagram.com\\\/exponor.porto\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/EXPONORtv\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"OnEvents Archives - Exponor","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"OnEvents Archives - Exponor","og_url":"https:\/\/exponor.pt\/en\/organizador_calendario\/onevents\/","og_site_name":"Exponor","og_image":[{"width":1200,"height":675,"url":"https:\/\/exponor.pt\/wp-content\/uploads\/2025\/06\/redesociais_exponor.webp","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/exponor.pt\/en\/organizador_calendario\/onevents\/","url":"https:\/\/exponor.pt\/en\/organizador_calendario\/onevents\/","name":"OnEvents Archives - Exponor","isPartOf":{"@id":"https:\/\/exponor.pt\/en\/#website"},"breadcrumb":{"@id":"https:\/\/exponor.pt\/en\/organizador_calendario\/onevents\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/exponor.pt\/en\/organizador_calendario\/onevents\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/exponor.pt\/en\/"},{"@type":"ListItem","position":2,"name":"OnEvents"}]},{"@type":"WebSite","@id":"https:\/\/exponor.pt\/en\/#website","url":"https:\/\/exponor.pt\/en\/","name":"Exponor","description":"Feira Internacional do Porto","publisher":{"@id":"https:\/\/exponor.pt\/en\/#organization"},"alternateName":"Feira Internacional do Porto","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exponor.pt\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/exponor.pt\/en\/#organization","name":"Exponor","alternateName":"Feira Internacional do Porto","url":"https:\/\/exponor.pt\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/exponor.pt\/en\/#\/schema\/logo\/image\/","url":"https:\/\/exponor.pt\/wp-content\/uploads\/2025\/05\/FavIcon.jpg","contentUrl":"https:\/\/exponor.pt\/wp-content\/uploads\/2025\/05\/FavIcon.jpg","width":500,"height":499,"caption":"Exponor"},"image":{"@id":"https:\/\/exponor.pt\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/exponor.fiporto\/","https:\/\/www.linkedin.com\/company\/exponor-fiporto","https:\/\/www.instagram.com\/exponor.porto\/","https:\/\/www.youtube.com\/user\/EXPONORtv"]}]}},"_links":{"self":[{"href":"https:\/\/exponor.pt\/en\/wp-json\/wp\/v2\/organizador_calendario\/259","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exponor.pt\/en\/wp-json\/wp\/v2\/organizador_calendario"}],"about":[{"href":"https:\/\/exponor.pt\/en\/wp-json\/wp\/v2\/taxonomies\/organizador_calendario"}],"wp:post_type":[{"href":"https:\/\/exponor.pt\/en\/wp-json\/wp\/v2\/calendario?organizador_calendario=259"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}